{"id":2335,"date":"2024-07-09T15:59:47","date_gmt":"2024-07-09T18:59:47","guid":{"rendered":"https:\/\/cpaatlantic.ca\/fr\/?p=2335"},"modified":"2024-08-13T16:06:52","modified_gmt":"2024-08-13T19:06:52","slug":"the-university-students-roadmap-to-becoming-a-cpa","status":"publish","type":"post","link":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/","title":{"rendered":"Feuille de route pour les \u00e9tudiants universitaires souhaitant devenir CPA"},"content":{"rendered":"\n<p>Est-ce que vous \u00eates \u00e9tudiant \u00e0 l\u2019universit\u00e9 et vous vous interrogez sur votre orientation professionnelle? Est-ce que vous avez envisag\u00e9 de devenir comptable professionnel agr\u00e9\u00e9 (CPA) avec tous les avantages que cela comporte? Voyons pourquoi il s\u2019agit d\u2019une carri\u00e8re qui m\u00e9rite vraiment le d\u00e9tour. Voici cinq tr\u00e8s bonnes raisons de devenir CPA afin de conna\u00eetre la r\u00e9ussite professionnelle et quelques conseils d\u2019une valeur inestimable pour vous lancer alors m\u00eame que vous \u00eates encore \u00e0 l\u2019universit\u00e9.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Gamme infinie de possibilit\u00e9s<\/strong>&nbsp;\u2013&nbsp;Vous pouvez, en tant que CPA, travailler dans absolument tous les secteurs, que vous vous passionniez pour la gestion de patrimoine, la protection de l\u2019environnement ou m\u00eame de toutes nouvelles industries comme la culture du cannabis. Il existe un monde illimit\u00e9 de possibilit\u00e9s, allant de r\u00f4les conventionnels dans l\u2019industrie financi\u00e8re \u00e0 des postes \u00e0 la fine pointe sur les plateformes num\u00e9riques.<\/li>\n\n\n\n<li><strong>Diversit\u00e9 des r\u00f4les<\/strong> \u2013&nbsp;Le titre de CPA vous ouvre la porte \u00e0 toutes sortes de r\u00f4les dans toutes sortes d\u2019industries, que vous souhaitiez devenir vice-pr\u00e9sident aux finances d\u2019une \u00e9quipe sportive professionnelle ou v\u00e9rificateur judiciaire international ou encore lancer votre propre entreprise.<\/li>\n\n\n\n<li><strong>Rayonnement international<\/strong> \u2013 L\u2019un des aspects les plus attrayants du titre de CPA est qu\u2019il vous donne la possibilit\u00e9 de travailler n\u2019importe o\u00f9 dans le monde. Que vous r\u00eaviez de travailler dans le quartier dynamique des affaires \u00e0 Toronto, d\u2019exercer dans le cadre paisible de l\u2019\u00eele Fogo \u00e0 Terre-Neuve ou m\u00eame d\u2019explorer des d\u00e9bouch\u00e9s \u00e0 l\u2019\u00e9tranger, en Europe, aux \u00c9tats-Unis, aux Cara\u00efbes ou en Asie, le monde entier est \u00e0 vos pieds.<\/li>\n\n\n\n<li><strong>S\u00e9curit\u00e9 de l\u2019emploi et salaire concurrentiel<\/strong> \u2013 Avec plus de 220&nbsp;000 CPA dans le monde et une demande soutenue chez les employeurs, le domaine de la comptabilit\u00e9 offre une s\u00e9curit\u00e9 de l\u2019emploi sans pareille. En outre, les CPA ont un salaire tr\u00e8s concurrentiel, ce qui rend cette orientation professionnelle encore plus attrayante.<\/li>\n\n\n\n<li><strong>Possibilit\u00e9s de faire profiter la collectivit\u00e9 de votre r\u00e9ussite<\/strong> \u2013 Au-del\u00e0 de la r\u00e9ussite financi\u00e8re, vous avez, en tant que CPA, les moyens de toucher la collectivit\u00e9. Vous pouvez faire du b\u00e9n\u00e9volat en tant que tr\u00e9sorier dans une organisation non gouvernementale, devenir un leader respect\u00e9 dans votre communaut\u00e9, etc. Le titre de CPA vous offre toutes sortes de possibilit\u00e9s de faire profiter la collectivit\u00e9 de votre prosp\u00e9rit\u00e9.<\/li>\n<\/ol>\n\n\n\n<p>Voici quelques conseils pour vous mettre sur la bonne voie alors m\u00eame que vous \u00eates encore aux \u00e9tudes \u00e0 l\u2019universit\u00e9&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Impliquez-vous<\/strong> \u2013&nbsp;Adh\u00e9rez aux associations en comptabilit\u00e9, en commerce ou en gestion sur le campus de votre universit\u00e9 afin de d\u00e9velopper votre r\u00e9seau de relations avec vos camarades et avec les sp\u00e9cialistes professionnels du secteur. Ces associations organisent souvent des \u00e9v\u00e9nements, des ateliers et des activit\u00e9s de r\u00e9seautage qui vous permettront de mieux comprendre l\u2019industrie.<\/li>\n\n\n\n<li><strong>Choisissez le bon programme universitaire<\/strong> \u2013 Choisissez une majeure ou un programme qui vous permettra de suivre certains des cours pr\u00e9paratoires \u00e0 la formation de CPA dans le cadre de vos \u00e9tudes. Cela simplifiera votre parcours pour devenir CPA et garantira que vous r\u00e9pondez bien \u00e0 toutes les exigences de formation th\u00e9orique. Vous trouverez le <a href=\"https:\/\/cpaatlantic.ca\/fr\/transfer-credit-guides\/\">guide de cr\u00e9dit de transfert<\/a> avec la liste des cours offerts dans les universit\u00e9s et les coll\u00e8ges du Canada atlantique et des Bermudes qui sont \u00e9quivalents aux cours pr\u00e9alables \u00e0 la formation du programme de formation professionnelle (PFP) des CPA.<br>Et si vous suivez un programme dans une discipline autre que les affaires, ne vous inqui\u00e9tez pas! Vous pouvez malgr\u00e9 tout devenir CPA. Pour en savoir plus, <a href=\"https:\/\/cpaatlantic.ca\/fr\/blog\/how-to-become-a-cpa-without-a-business-degree\/\">cliquez ici.<\/a><\/li>\n\n\n\n<li><strong>Utilisez les service d\u2019orientation <\/strong>\u2013 Profitez des services d\u2019orientation professionnelle offerts par votre universit\u00e9 et participez aux salons de l\u2019emploi afin d\u2019explorer les possibilit\u00e9s de stage et les offres d\u2019emploi dans la comptabilit\u00e9. En d\u00e9veloppant d\u00e8s maintenant votre r\u00e9seau de relations, vous vous mettrez sur la voie de la r\u00e9ussite dans votre carri\u00e8re de CPA.<\/li>\n\n\n\n<li><strong>Envisagez un programme en alternance travail-\u00e9tudes<\/strong> \u2013 Si vous en avez la possibilit\u00e9, envisagez de vous inscrire \u00e0 un programme en alternance travail-\u00e9tudes afin d\u2019acqu\u00e9rir une exp\u00e9rience professionnelle utile dans la comptabilit\u00e9. Les stages en alternance travail-\u00e9tudes dotent les \u00e9tudiants d\u2019une exp\u00e9rience pratique d\u2019une valeur inestimable et permettent de sortir du lot quand on postule aupr\u00e8s d\u2019employeurs apr\u00e8s l\u2019obtention de son dipl\u00f4me.<\/li>\n<\/ul>\n\n\n\n<p>L\u2019obtention du titre de CPA vous ouvrira tout un monde de possibilit\u00e9s et d\u2019avantages. En profitant des avantages du titre de CPA et en prenant les devants avec des d\u00e9marches d\u00e8s maintenant pour vous pr\u00e9parer \u00e0 votre future carri\u00e8re alors m\u00eame que vous \u00eates encore \u00e0 l\u2019universit\u00e9, vous ferez un grand pas vers la r\u00e9ussite dans le domaine passionnant et gratifiant de la comptabilit\u00e9. <\/p>\n\n\n\n<p>Pour en savoir plus, entrez un <a href=\"https:\/\/cpaatlantic.ca\/fr\/#cpaa-form-tabs\">contact avec un conseiller<\/a> au recrutement des \u00e9tudiants et discutez avec lui de votre parcours menant au titre de CPA. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est-ce que vous \u00eates \u00e9tudiant \u00e0 l\u2019universit\u00e9 et vous vous interrogez sur votre orientation professionnelle? Est-ce que vous avez envisag\u00e9 de devenir comptable professionnel &#8230;<\/p>\n","protected":false},"author":4,"featured_media":2336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[13,12,15],"class_list":["post-2335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-comptables-professionnels-agrees","tag-cpa","tag-devenez-cpa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feuille de route pour les \u00e9tudiants universitaires souhaitant devenir CPA - CPA Atlantique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feuille de route pour les \u00e9tudiants universitaires souhaitant devenir CPA - CPA Atlantique\" \/>\n<meta property=\"og:description\" content=\"Est-ce que vous \u00eates \u00e9tudiant \u00e0 l\u2019universit\u00e9 et vous vous interrogez sur votre orientation professionnelle? Est-ce que vous avez envisag\u00e9 de devenir comptable professionnel ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/\" \/>\n<meta property=\"og:site_name\" content=\"CPA Atlantique\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-09T18:59:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-13T19:06:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpaatlantic.ca\/fr\/wp-content\/uploads\/sites\/3\/2024\/08\/PursueCPAinUniversityclass_Desktop-925-x-600-px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"925\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hgillis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"hgillis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/\"},\"author\":{\"name\":\"hgillis\",\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/897a67978a69b19f0bd045beac61baac\"},\"headline\":\"Feuille de route pour les \u00e9tudiants universitaires souhaitant devenir CPA\",\"datePublished\":\"2024-07-09T18:59:47+00:00\",\"dateModified\":\"2024-08-13T19:06:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/\"},\"wordCount\":875,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/PursueCPAinUniversityclass_Desktop-925-x-600-px.jpg\",\"keywords\":[\"comptables professionnels agr\u00e9\u00e9s\",\"CPA\",\"Devenez CPA\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/\",\"url\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/\",\"name\":\"Feuille de route pour les \u00e9tudiants universitaires souhaitant devenir CPA - CPA Atlantique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/PursueCPAinUniversityclass_Desktop-925-x-600-px.jpg\",\"datePublished\":\"2024-07-09T18:59:47+00:00\",\"dateModified\":\"2024-08-13T19:06:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/897a67978a69b19f0bd045beac61baac\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/PursueCPAinUniversityclass_Desktop-925-x-600-px.jpg\",\"contentUrl\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/PursueCPAinUniversityclass_Desktop-925-x-600-px.jpg\",\"width\":925,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/the-university-students-roadmap-to-becoming-a-cpa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feuille de route pour les \u00e9tudiants universitaires souhaitant devenir CPA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/\",\"name\":\"CPA Atlantique\",\"description\":\"Devenir CPA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/897a67978a69b19f0bd045beac61baac\",\"name\":\"hgillis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dcb8cfa668583f670f7838b77fb99306461f84824ca711014beeb4efa45b584?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dcb8cfa668583f670f7838b77fb99306461f84824ca711014beeb4efa45b584?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dcb8cfa668583f670f7838b77fb99306461f84824ca711014beeb4efa45b584?s=96&d=mm&r=g\",\"caption\":\"hgillis\"},\"url\":\"https:\\\/\\\/cpaatlantic.ca\\\/fr\\\/blog\\\/author\\\/hgillis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feuille de route pour les \u00e9tudiants universitaires souhaitant devenir CPA - CPA Atlantique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/","og_locale":"en_US","og_type":"article","og_title":"Feuille de route pour les \u00e9tudiants universitaires souhaitant devenir CPA - CPA Atlantique","og_description":"Est-ce que vous \u00eates \u00e9tudiant \u00e0 l\u2019universit\u00e9 et vous vous interrogez sur votre orientation professionnelle? Est-ce que vous avez envisag\u00e9 de devenir comptable professionnel ...","og_url":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/","og_site_name":"CPA Atlantique","article_published_time":"2024-07-09T18:59:47+00:00","article_modified_time":"2024-08-13T19:06:52+00:00","og_image":[{"width":925,"height":600,"url":"https:\/\/cpaatlantic.ca\/fr\/wp-content\/uploads\/sites\/3\/2024\/08\/PursueCPAinUniversityclass_Desktop-925-x-600-px.jpg","type":"image\/jpeg"}],"author":"hgillis","twitter_card":"summary_large_image","twitter_misc":{"Written by":"hgillis","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/#article","isPartOf":{"@id":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/"},"author":{"name":"hgillis","@id":"https:\/\/cpaatlantic.ca\/fr\/#\/schema\/person\/897a67978a69b19f0bd045beac61baac"},"headline":"Feuille de route pour les \u00e9tudiants universitaires souhaitant devenir CPA","datePublished":"2024-07-09T18:59:47+00:00","dateModified":"2024-08-13T19:06:52+00:00","mainEntityOfPage":{"@id":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/"},"wordCount":875,"commentCount":0,"image":{"@id":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/#primaryimage"},"thumbnailUrl":"https:\/\/cpaatlantic.ca\/fr\/wp-content\/uploads\/sites\/3\/2024\/08\/PursueCPAinUniversityclass_Desktop-925-x-600-px.jpg","keywords":["comptables professionnels agr\u00e9\u00e9s","CPA","Devenez CPA"],"articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/","url":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/","name":"Feuille de route pour les \u00e9tudiants universitaires souhaitant devenir CPA - CPA Atlantique","isPartOf":{"@id":"https:\/\/cpaatlantic.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/#primaryimage"},"image":{"@id":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/#primaryimage"},"thumbnailUrl":"https:\/\/cpaatlantic.ca\/fr\/wp-content\/uploads\/sites\/3\/2024\/08\/PursueCPAinUniversityclass_Desktop-925-x-600-px.jpg","datePublished":"2024-07-09T18:59:47+00:00","dateModified":"2024-08-13T19:06:52+00:00","author":{"@id":"https:\/\/cpaatlantic.ca\/fr\/#\/schema\/person\/897a67978a69b19f0bd045beac61baac"},"breadcrumb":{"@id":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/#primaryimage","url":"https:\/\/cpaatlantic.ca\/fr\/wp-content\/uploads\/sites\/3\/2024\/08\/PursueCPAinUniversityclass_Desktop-925-x-600-px.jpg","contentUrl":"https:\/\/cpaatlantic.ca\/fr\/wp-content\/uploads\/sites\/3\/2024\/08\/PursueCPAinUniversityclass_Desktop-925-x-600-px.jpg","width":925,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/cpaatlantic.ca\/fr\/blog\/the-university-students-roadmap-to-becoming-a-cpa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpaatlantic.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Feuille de route pour les \u00e9tudiants universitaires souhaitant devenir CPA"}]},{"@type":"WebSite","@id":"https:\/\/cpaatlantic.ca\/fr\/#website","url":"https:\/\/cpaatlantic.ca\/fr\/","name":"CPA Atlantique","description":"Devenir CPA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpaatlantic.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/cpaatlantic.ca\/fr\/#\/schema\/person\/897a67978a69b19f0bd045beac61baac","name":"hgillis","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7dcb8cfa668583f670f7838b77fb99306461f84824ca711014beeb4efa45b584?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7dcb8cfa668583f670f7838b77fb99306461f84824ca711014beeb4efa45b584?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7dcb8cfa668583f670f7838b77fb99306461f84824ca711014beeb4efa45b584?s=96&d=mm&r=g","caption":"hgillis"},"url":"https:\/\/cpaatlantic.ca\/fr\/blog\/author\/hgillis\/"}]}},"_links":{"self":[{"href":"https:\/\/cpaatlantic.ca\/fr\/wp-json\/wp\/v2\/posts\/2335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpaatlantic.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpaatlantic.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpaatlantic.ca\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cpaatlantic.ca\/fr\/wp-json\/wp\/v2\/comments?post=2335"}],"version-history":[{"count":2,"href":"https:\/\/cpaatlantic.ca\/fr\/wp-json\/wp\/v2\/posts\/2335\/revisions"}],"predecessor-version":[{"id":2338,"href":"https:\/\/cpaatlantic.ca\/fr\/wp-json\/wp\/v2\/posts\/2335\/revisions\/2338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpaatlantic.ca\/fr\/wp-json\/wp\/v2\/media\/2336"}],"wp:attachment":[{"href":"https:\/\/cpaatlantic.ca\/fr\/wp-json\/wp\/v2\/media?parent=2335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpaatlantic.ca\/fr\/wp-json\/wp\/v2\/categories?post=2335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpaatlantic.ca\/fr\/wp-json\/wp\/v2\/tags?post=2335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}